{"id":4146,"date":"2016-09-26T09:38:31","date_gmt":"2016-09-26T09:38:31","guid":{"rendered":"https:\/\/demo.yolotheme.com\/behealth\/?page_id=4146"},"modified":"2021-03-26T09:23:47","modified_gmt":"2021-03-26T09:23:47","slug":"original-home","status":"publish","type":"page","link":"https:\/\/demo.yolotheme.com\/behealth\/original-home\/","title":{"rendered":"Original Home"},"content":{"rendered":"<p>[vc_row][vc_column][rev_slider_vc alias=&#8221;home-5&#8243;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1475305334529{margin-top: 5% !important;margin-bottom: 3% !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Welcome to BeHealth.&#8221; font_container=&#8221;tag:h2|font_size:48px|text_align:center|color:%230c0c0c&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1475305228183{margin-top: 0px !important;margin-bottom: 0px !important;}&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1474884525604{padding-top: 2% !important;padding-bottom: 4% !important;}&#8221;][vc_column offset=&#8221;vc_col-lg-5 vc_col-md-5&#8243; css=&#8221;.vc_custom_1476159651333{margin-bottom: 20px !important;}&#8221;][vc_single_image image=&#8221;3391&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column offset=&#8221;vc_col-lg-7 vc_col-md-7&#8243;][vc_row_inner css=&#8221;.vc_custom_1474885701018{padding-right: 0px !important;padding-left: 0px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]             <div class=\" \" >\r\n                \r\n<div class=\"row image-box-style style4\">\r\n\t<div class=\"col-xs-12 img-box-img\">\r\n\t\t<div class=\"col-xs-3 img-box\">\r\n\t\t<div class=\"style4-icon\">\r\n\t\t\t\t\t<a href=\"\">\r\n\t\t\t\t\t<img src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/08\/icon-img1.png\"  class=\"img-responsive\" alt=\"Experienced trainers\"\/>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-title\">Experienced trainers<\/div><\/div>\r\n\t<\/div>\r\n\t<div class=\"col-xs-12 img-box-content\">\r\n\t\t<div class=\"col-xs-3\"><\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-content\">With more than 10 years of experiences professional lessons<\/div><\/div>\r\n\t<\/div>\r\n<\/div>            <\/div>\r\n                         <div class=\" \" >\r\n                \r\n<div class=\"row image-box-style style4\">\r\n\t<div class=\"col-xs-12 img-box-img\">\r\n\t\t<div class=\"col-xs-3 img-box\">\r\n\t\t<div class=\"style4-icon\">\r\n\t\t\t\t\t<a href=\"\">\r\n\t\t\t\t\t<img src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/08\/icon-img2.png\"  class=\"img-responsive\" alt=\"Kudalini Yoga\"\/>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-title\">Kudalini Yoga<\/div><\/div>\r\n\t<\/div>\r\n\t<div class=\"col-xs-12 img-box-content\">\r\n\t\t<div class=\"col-xs-3\"><\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-content\">With more than 10 years of experiences professional lessons<\/div><\/div>\r\n\t<\/div>\r\n<\/div>            <\/div>\r\n                         <div class=\" \" >\r\n                \r\n<div class=\"row image-box-style style4\">\r\n\t<div class=\"col-xs-12 img-box-img\">\r\n\t\t<div class=\"col-xs-3 img-box\">\r\n\t\t<div class=\"style4-icon\">\r\n\t\t\t\t\t<a href=\"\">\r\n\t\t\t\t\t<img src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/08\/icon-img3.png\"  class=\"img-responsive\" alt=\"Kundalm Yoga\"\/>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-title\">Kundalm Yoga<\/div><\/div>\r\n\t<\/div>\r\n\t<div class=\"col-xs-12 img-box-content\">\r\n\t\t<div class=\"col-xs-3\"><\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-content\">With more than 10 years of experiences professional lessons<\/div><\/div>\r\n\t<\/div>\r\n<\/div>            <\/div>\r\n            [\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;]             <div class=\" \" >\r\n                \r\n<div class=\"row image-box-style style4\">\r\n\t<div class=\"col-xs-12 img-box-img\">\r\n\t\t<div class=\"col-xs-3 img-box\">\r\n\t\t<div class=\"style4-icon\">\r\n\t\t\t\t\t<a href=\"\">\r\n\t\t\t\t\t<img src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/08\/icon-img4.png\"  class=\"img-responsive\" alt=\"Pregnant Yoga\"\/>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-title\">Pregnant Yoga<\/div><\/div>\r\n\t<\/div>\r\n\t<div class=\"col-xs-12 img-box-content\">\r\n\t\t<div class=\"col-xs-3\"><\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-content\">With more than 10 years of experiences professional lessons<\/div><\/div>\r\n\t<\/div>\r\n<\/div>            <\/div>\r\n                         <div class=\" \" >\r\n                \r\n<div class=\"row image-box-style style4\">\r\n\t<div class=\"col-xs-12 img-box-img\">\r\n\t\t<div class=\"col-xs-3 img-box\">\r\n\t\t<div class=\"style4-icon\">\r\n\t\t\t\t\t<a href=\"\">\r\n\t\t\t\t\t<img src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/08\/icon-img.png\"  class=\"img-responsive\" alt=\"Meditation Yoga\"\/>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-title\">Meditation Yoga<\/div><\/div>\r\n\t<\/div>\r\n\t<div class=\"col-xs-12 img-box-content\">\r\n\t\t<div class=\"col-xs-3\"><\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-content\">With more than 10 years of experiences professional lessons<\/div><\/div>\r\n\t<\/div>\r\n<\/div>            <\/div>\r\n                         <div class=\" \" >\r\n                \r\n<div class=\"row image-box-style style4\">\r\n\t<div class=\"col-xs-12 img-box-img\">\r\n\t\t<div class=\"col-xs-3 img-box\">\r\n\t\t<div class=\"style4-icon\">\r\n\t\t\t\t\t<a href=\"\">\r\n\t\t\t\t\t<img src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/08\/icon-img2-1.png\"  class=\"img-responsive\" alt=\"Lyengar Yoga\"\/>\r\n\t\t\t\t\t<\/a>\r\n\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-title\">Lyengar Yoga<\/div><\/div>\r\n\t<\/div>\r\n\t<div class=\"col-xs-12 img-box-content\">\r\n\t\t<div class=\"col-xs-3\"><\/div>\r\n\t\t<div class=\"col-xs-9\"><div class=\"image-box-content\">With more than 10 years of experiences professional lessons<\/div><\/div>\r\n\t<\/div>\r\n<\/div>            <\/div>\r\n            [\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row parallax=&#8221;content-moving&#8221; css=&#8221;.vc_custom_1477044512260{padding-top: 5% !important;padding-bottom: 3% !important;background-image: url(https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/bg-paralax4.jpg?id=4880) !important;background-position: center;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;News Events Of Week.&#8221; font_container=&#8221;tag:h1|font_size:48px|text_align:center|color:%23ffffff&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1476160083821{margin-top: 0px !important;}&#8221;][vc_column_text css=&#8221;.vc_custom_1476763692026{margin-bottom: 30px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">Lorem ipsum dolor sit amet, taciti purus fugiat sed. Vitae sed sed velit aliquam suspendisse.<\/span><\/p>\n<p>[\/vc_column_text]            <div class=\" \" >\r\n                \r\n<div class=\"events-show-slide\">\r\n\t<ul id=\"yoga-class-slide\" class=\"yogas yoga-class-slide owl-carousel\"\r\n        data-owl=\"3\"\r\n        data-rtl=\"\"\r\n        data-loop=\"true\"\r\n        data-margin=\"30\"\r\n        data-autoplay=\"true\"\r\n        data-duration=\"4000\"\r\n        data-nav=\"true\"\r\n    >\r\n            <li>\r\n            <div class=\"bg-events-show\">\r\n                <a href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/yoga-journal-live\/\">\r\n                    <div class=\"event-thumbnail\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-1-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-1-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-1-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-1.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                        <div class=\"events-show-date\">\r\n                            <div class=\"events-show-time-date\">22<\/div>\r\n                            <div class=\"events-show-time-month\">Sep<\/div>\r\n                        <\/div>\r\n                        <h6 class=\"events-show-title\">Yoga Journal Live<\/h6>\r\n                    <\/div>\r\n                <\/a>\r\n                <div class=\"events-content\">\r\n                    <div class=\"events-show-time\">\r\n                    <i class=\"fa fa-clock-o\" aria-hidden=\"true\"><\/i> 09:00 - 10:00                <\/div>\r\n                <a class=\"events-show-btn-join\" href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/yoga-journal-live\/\">Join Now!<\/a>\r\n                <\/div>  \r\n            <\/div>\r\n        <\/li>\r\n            <li>\r\n            <div class=\"bg-events-show\">\r\n                <a href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/hanuman-yoga-festival-2\/\">\r\n                    <div class=\"event-thumbnail\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-2-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-2-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-2-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-2.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                        <div class=\"events-show-date\">\r\n                            <div class=\"events-show-time-date\">22<\/div>\r\n                            <div class=\"events-show-time-month\">Sep<\/div>\r\n                        <\/div>\r\n                        <h6 class=\"events-show-title\">Hanuman Yoga Festival<\/h6>\r\n                    <\/div>\r\n                <\/a>\r\n                <div class=\"events-content\">\r\n                    <div class=\"events-show-time\">\r\n                    <i class=\"fa fa-clock-o\" aria-hidden=\"true\"><\/i> 08:25 - 10:00                <\/div>\r\n                <a class=\"events-show-btn-join\" href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/hanuman-yoga-festival-2\/\">Join Now!<\/a>\r\n                <\/div>  \r\n            <\/div>\r\n        <\/li>\r\n            <li>\r\n            <div class=\"bg-events-show\">\r\n                <a href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/hanuman-yoga-festival\/\">\r\n                    <div class=\"event-thumbnail\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-2-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-2-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-2-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-2.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                        <div class=\"events-show-date\">\r\n                            <div class=\"events-show-time-date\">22<\/div>\r\n                            <div class=\"events-show-time-month\">Sep<\/div>\r\n                        <\/div>\r\n                        <h6 class=\"events-show-title\">Hanuman Yoga Festival<\/h6>\r\n                    <\/div>\r\n                <\/a>\r\n                <div class=\"events-content\">\r\n                    <div class=\"events-show-time\">\r\n                    <i class=\"fa fa-clock-o\" aria-hidden=\"true\"><\/i> 08:25 - 10:00                <\/div>\r\n                <a class=\"events-show-btn-join\" href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/hanuman-yoga-festival\/\">Join Now!<\/a>\r\n                <\/div>  \r\n            <\/div>\r\n        <\/li>\r\n            <li>\r\n            <div class=\"bg-events-show\">\r\n                <a href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/last-friday-flow-with-dj-drishti\/\">\r\n                    <div class=\"event-thumbnail\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-4-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-4-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-4-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-4.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                        <div class=\"events-show-date\">\r\n                            <div class=\"events-show-time-date\">31<\/div>\r\n                            <div class=\"events-show-time-month\">Jul<\/div>\r\n                        <\/div>\r\n                        <h6 class=\"events-show-title\">Last Friday Flow with DJ Drishti<\/h6>\r\n                    <\/div>\r\n                <\/a>\r\n                <div class=\"events-content\">\r\n                    <div class=\"events-show-time\">\r\n                    <i class=\"fa fa-clock-o\" aria-hidden=\"true\"><\/i> 09:00 - 10:00                <\/div>\r\n                <a class=\"events-show-btn-join\" href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/last-friday-flow-with-dj-drishti\/\">Join Now!<\/a>\r\n                <\/div>  \r\n            <\/div>\r\n        <\/li>\r\n            <li>\r\n            <div class=\"bg-events-show\">\r\n                <a href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/introduction-to-heartfull-meditation\/\">\r\n                    <div class=\"event-thumbnail\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-3-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-3-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-3-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-3.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                        <div class=\"events-show-date\">\r\n                            <div class=\"events-show-time-date\">24<\/div>\r\n                            <div class=\"events-show-time-month\">Jul<\/div>\r\n                        <\/div>\r\n                        <h6 class=\"events-show-title\">Introduction to Heartfull Meditation<\/h6>\r\n                    <\/div>\r\n                <\/a>\r\n                <div class=\"events-content\">\r\n                    <div class=\"events-show-time\">\r\n                    <i class=\"fa fa-clock-o\" aria-hidden=\"true\"><\/i> 09:00 - 10:00                <\/div>\r\n                <a class=\"events-show-btn-join\" href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/introduction-to-heartfull-meditation\/\">Join Now!<\/a>\r\n                <\/div>  \r\n            <\/div>\r\n        <\/li>\r\n            <li>\r\n            <div class=\"bg-events-show\">\r\n                <a href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/stretch-your-body\/\">\r\n                    <div class=\"event-thumbnail\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-5-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-5-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-5-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-5.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                        <div class=\"events-show-date\">\r\n                            <div class=\"events-show-time-date\">22<\/div>\r\n                            <div class=\"events-show-time-month\">Jul<\/div>\r\n                        <\/div>\r\n                        <h6 class=\"events-show-title\">Stretch your body<\/h6>\r\n                    <\/div>\r\n                <\/a>\r\n                <div class=\"events-content\">\r\n                    <div class=\"events-show-time\">\r\n                    <i class=\"fa fa-clock-o\" aria-hidden=\"true\"><\/i> 09:00 - 10:00                <\/div>\r\n                <a class=\"events-show-btn-join\" href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/stretch-your-body\/\">Join Now!<\/a>\r\n                <\/div>  \r\n            <\/div>\r\n        <\/li>\r\n            <li>\r\n            <div class=\"bg-events-show\">\r\n                <a href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/be-a-family-for-healthy\/\">\r\n                    <div class=\"event-thumbnail\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-7-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-7-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-7-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-7.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                        <div class=\"events-show-date\">\r\n                            <div class=\"events-show-time-date\">22<\/div>\r\n                            <div class=\"events-show-time-month\">Jul<\/div>\r\n                        <\/div>\r\n                        <h6 class=\"events-show-title\">Be a Family for Healthy<\/h6>\r\n                    <\/div>\r\n                <\/a>\r\n                <div class=\"events-content\">\r\n                    <div class=\"events-show-time\">\r\n                    <i class=\"fa fa-clock-o\" aria-hidden=\"true\"><\/i> 09:00 - 10:00                <\/div>\r\n                <a class=\"events-show-btn-join\" href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/be-a-family-for-healthy\/\">Join Now!<\/a>\r\n                <\/div>  \r\n            <\/div>\r\n        <\/li>\r\n            <li>\r\n            <div class=\"bg-events-show\">\r\n                <a href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/pratice-in-italia\/\">\r\n                    <div class=\"event-thumbnail\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-9-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-9-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-9-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-9.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                        <div class=\"events-show-date\">\r\n                            <div class=\"events-show-time-date\">22<\/div>\r\n                            <div class=\"events-show-time-month\">Jul<\/div>\r\n                        <\/div>\r\n                        <h6 class=\"events-show-title\">Pratice In Italia<\/h6>\r\n                    <\/div>\r\n                <\/a>\r\n                <div class=\"events-content\">\r\n                    <div class=\"events-show-time\">\r\n                    <i class=\"fa fa-clock-o\" aria-hidden=\"true\"><\/i> 09:00 - 10:00                <\/div>\r\n                <a class=\"events-show-btn-join\" href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/pratice-in-italia\/\">Join Now!<\/a>\r\n                <\/div>  \r\n            <\/div>\r\n        <\/li>\r\n            <li>\r\n            <div class=\"bg-events-show\">\r\n                <a href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/yoga-times-and-the-happy-health\/\">\r\n                    <div class=\"event-thumbnail\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-8-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-8-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-8-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/event-8.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                        <div class=\"events-show-date\">\r\n                            <div class=\"events-show-time-date\">22<\/div>\r\n                            <div class=\"events-show-time-month\">Jul<\/div>\r\n                        <\/div>\r\n                        <h6 class=\"events-show-title\">Yoga and the Happy Health<\/h6>\r\n                    <\/div>\r\n                <\/a>\r\n                <div class=\"events-content\">\r\n                    <div class=\"events-show-time\">\r\n                    <i class=\"fa fa-clock-o\" aria-hidden=\"true\"><\/i> 09:00 - 10:00                <\/div>\r\n                <a class=\"events-show-btn-join\" href=\"https:\/\/demo.yolotheme.com\/behealth\/event\/yoga-times-and-the-happy-health\/\">Join Now!<\/a>\r\n                <\/div>  \r\n            <\/div>\r\n        <\/li>\r\n        <\/ul>\r\n<\/div>            <\/div> \r\n        [\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1475305566215{padding-top: 4% !important;padding-bottom: 4.5% !important;background-image: url(https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/bg-class-home1.jpg?id=3542) !important;}&#8221;][vc_column css=&#8221;.vc_custom_1472453743457{padding-right: 0px !important;padding-left: 0px !important;}&#8221;][vc_custom_heading text=&#8221;Our Yoga Fitness Classes&#8221; font_container=&#8221;tag:h1|font_size:36px|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1475305453693{margin-bottom: 6% !important;}&#8221;]  \r\n                    <div class=\"yoga-class-grid_style \" >\r\n                <div id=\"yolo-yoga\" class=\"yolo-yoga\">\r\n    <ul id=\"yoga-class-grid\" class=\"yogas yoga-class-grid owl-carousel owl-theme\">\r\n        \r\n        <li class=\"classes-grid-li\">\r\n\t\r\n\t\t<!-- Slide row -->\r\n    <div class=\"row\">\r\n\t\r\n\t<article class=\"col-xs-12 col-sm-6\">\r\n\t\t<div class=\"yoga-classes-wrap\">\r\n\t\t\t<h3 class=\"yoga-title-classes\">Class: Advanced Yoga<\/h3>\r\n\t    \t<div class=\"yoga-class-content clearfix\">\r\n    \t\t\t<div class=\"yoga-image-classes\">\r\n                    <a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class6-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class6-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class6-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class6.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                    <\/a>\r\n                <\/div>\r\n\t    \t\t<div class=\"yoga-class-info\">\r\n\t    \t\t\t<div class=\"yoga-trainer\">teacher: Vytas Skas<\/div>\r\n\t\t\t    \t<div class=\"yoga-desc-class-1\">December 10, 2016<\/div>\r\n\t\t\t        <div class=\"yoga-desc-class-2\">\r\n                    9:00am - 10:00am                    <\/div>\r\n\t\t\t        <div class=\"join-yoga-class\"><a class=\"yoga-join-now-btn\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\">\r\n                        <span class=\"effect\">Join now!<\/span>\r\n                        <span class=\"effect-hover\">Join now!<\/span>\r\n                    <\/a><\/div>\r\n\t    \t\t<\/div>\r\n\t    \t<\/div>\r\n\t\t<\/div>\r\n    <\/article>\r\n\r\n    \r\n\t\r\n\t\r\n    \r\n    \r\n\t\r\n\t<article class=\"col-xs-12 col-sm-6\">\r\n\t\t<div class=\"yoga-classes-wrap\">\r\n\t\t\t<h3 class=\"yoga-title-classes\">Class: Basic Kundalini<\/h3>\r\n\t    \t<div class=\"yoga-class-content clearfix\">\r\n    \t\t\t<div class=\"yoga-image-classes\">\r\n                    <a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class1-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class1-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class1-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class1.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                    <\/a>\r\n                <\/div>\r\n\t    \t\t<div class=\"yoga-class-info\">\r\n\t    \t\t\t<div class=\"yoga-trainer\">teacher: Chris Kane<\/div>\r\n\t\t\t    \t<div class=\"yoga-desc-class-1\">December 10, 2016<\/div>\r\n\t\t\t        <div class=\"yoga-desc-class-2\">\r\n                    7:00am - 9:00am                    <\/div>\r\n\t\t\t        <div class=\"join-yoga-class\"><a class=\"yoga-join-now-btn\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\">\r\n                        <span class=\"effect\">Join now!<\/span>\r\n                        <span class=\"effect-hover\">Join now!<\/span>\r\n                    <\/a><\/div>\r\n\t    \t\t<\/div>\r\n\t    \t<\/div>\r\n\t\t<\/div>\r\n    <\/article>\r\n\r\n        <\/div><!-- End Slide row -->\r\n\t\r\n\t\r\n\t\r\n    \r\n    \r\n\t\t<!-- Slide row -->\r\n    <div class=\"row\">\r\n\t\r\n\t<article class=\"col-xs-12 col-sm-6\">\r\n\t\t<div class=\"yoga-classes-wrap\">\r\n\t\t\t<h3 class=\"yoga-title-classes\">Class: Pratice With Children<\/h3>\r\n\t    \t<div class=\"yoga-class-content clearfix\">\r\n    \t\t\t<div class=\"yoga-image-classes\">\r\n                    <a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class2-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class2-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class2-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class2.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                    <\/a>\r\n                <\/div>\r\n\t    \t\t<div class=\"yoga-class-info\">\r\n\t    \t\t\t<div class=\"yoga-trainer\">teacher: Adam rams<\/div>\r\n\t\t\t    \t<div class=\"yoga-desc-class-1\">December 1, 2016<\/div>\r\n\t\t\t        <div class=\"yoga-desc-class-2\">\r\n                    7:00am - 9:00am                    <\/div>\r\n\t\t\t        <div class=\"join-yoga-class\"><a class=\"yoga-join-now-btn\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\">\r\n                        <span class=\"effect\">Join now!<\/span>\r\n                        <span class=\"effect-hover\">Join now!<\/span>\r\n                    <\/a><\/div>\r\n\t    \t\t<\/div>\r\n\t    \t<\/div>\r\n\t\t<\/div>\r\n    <\/article>\r\n\r\n    \r\n\t\r\n\t\r\n    \r\n    \r\n\t\r\n\t<article class=\"col-xs-12 col-sm-6\">\r\n\t\t<div class=\"yoga-classes-wrap\">\r\n\t\t\t<h3 class=\"yoga-title-classes\">Class: Healthy Recipes<\/h3>\r\n\t    \t<div class=\"yoga-class-content clearfix\">\r\n    \t\t\t<div class=\"yoga-image-classes\">\r\n                    <a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class7-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class7-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class7-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class7.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                    <\/a>\r\n                <\/div>\r\n\t    \t\t<div class=\"yoga-class-info\">\r\n\t    \t\t\t<div class=\"yoga-trainer\">teacher: Vytas Skas<\/div>\r\n\t\t\t    \t<div class=\"yoga-desc-class-1\">December 1, 2016<\/div>\r\n\t\t\t        <div class=\"yoga-desc-class-2\">\r\n                    7:00am - 9:00am                    <\/div>\r\n\t\t\t        <div class=\"join-yoga-class\"><a class=\"yoga-join-now-btn\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\">\r\n                        <span class=\"effect\">Join now!<\/span>\r\n                        <span class=\"effect-hover\">Join now!<\/span>\r\n                    <\/a><\/div>\r\n\t    \t\t<\/div>\r\n\t    \t<\/div>\r\n\t\t<\/div>\r\n    <\/article>\r\n\r\n        <\/div><!-- End Slide row -->\r\n\t\r\n\t    <\/li>\r\n\t\r\n\t\r\n    \r\n        <li class=\"classes-grid-li\">\r\n\t\r\n\t\t<!-- Slide row -->\r\n    <div class=\"row\">\r\n\t\r\n\t<article class=\"col-xs-12 col-sm-6\">\r\n\t\t<div class=\"yoga-classes-wrap\">\r\n\t\t\t<h3 class=\"yoga-title-classes\">Class: Yoga For Student<\/h3>\r\n\t    \t<div class=\"yoga-class-content clearfix\">\r\n    \t\t\t<div class=\"yoga-image-classes\">\r\n                    <a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-student\/\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class3-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class3-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class3-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class3.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                    <\/a>\r\n                <\/div>\r\n\t    \t\t<div class=\"yoga-class-info\">\r\n\t    \t\t\t<div class=\"yoga-trainer\">teacher: Emily Blunt<\/div>\r\n\t\t\t    \t<div class=\"yoga-desc-class-1\">November 24, 2016<\/div>\r\n\t\t\t        <div class=\"yoga-desc-class-2\">\r\n                    9:00am - 10:00am                    <\/div>\r\n\t\t\t        <div class=\"join-yoga-class\"><a class=\"yoga-join-now-btn\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-student\/\">\r\n                        <span class=\"effect\">Join now!<\/span>\r\n                        <span class=\"effect-hover\">Join now!<\/span>\r\n                    <\/a><\/div>\r\n\t    \t\t<\/div>\r\n\t    \t<\/div>\r\n\t\t<\/div>\r\n    <\/article>\r\n\r\n    \r\n\t\r\n\t\r\n    \r\n    \r\n\t\r\n\t<article class=\"col-xs-12 col-sm-6\">\r\n\t\t<div class=\"yoga-classes-wrap\">\r\n\t\t\t<h3 class=\"yoga-title-classes\">Class: Nature Yoga<\/h3>\r\n\t    \t<div class=\"yoga-class-content clearfix\">\r\n    \t\t\t<div class=\"yoga-image-classes\">\r\n                    <a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/nature-yoga\/\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class5-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class5-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class5-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class5.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                    <\/a>\r\n                <\/div>\r\n\t    \t\t<div class=\"yoga-class-info\">\r\n\t    \t\t\t<div class=\"yoga-trainer\">teacher: Gabriel Jasical<\/div>\r\n\t\t\t    \t<div class=\"yoga-desc-class-1\">November 24, 2016<\/div>\r\n\t\t\t        <div class=\"yoga-desc-class-2\">\r\n                    7:00am - 9:00am                    <\/div>\r\n\t\t\t        <div class=\"join-yoga-class\"><a class=\"yoga-join-now-btn\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/nature-yoga\/\">\r\n                        <span class=\"effect\">Join now!<\/span>\r\n                        <span class=\"effect-hover\">Join now!<\/span>\r\n                    <\/a><\/div>\r\n\t    \t\t<\/div>\r\n\t    \t<\/div>\r\n\t\t<\/div>\r\n    <\/article>\r\n\r\n        <\/div><!-- End Slide row -->\r\n\t\r\n\t\r\n\t\r\n    \r\n    \r\n\t\t<!-- Slide row -->\r\n    <div class=\"row\">\r\n\t\r\n\t<article class=\"col-xs-12 col-sm-6\">\r\n\t\t<div class=\"yoga-classes-wrap\">\r\n\t\t\t<h3 class=\"yoga-title-classes\">Class: Basic Child Yoga<\/h3>\r\n\t    \t<div class=\"yoga-class-content clearfix\">\r\n    \t\t\t<div class=\"yoga-image-classes\">\r\n                    <a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-child-yoga\/\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class4-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class4-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class4-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class4.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                    <\/a>\r\n                <\/div>\r\n\t    \t\t<div class=\"yoga-class-info\">\r\n\t    \t\t\t<div class=\"yoga-trainer\">teacher: Rose Cymbal<\/div>\r\n\t\t\t    \t<div class=\"yoga-desc-class-1\">November 18, 2016<\/div>\r\n\t\t\t        <div class=\"yoga-desc-class-2\">\r\n                    7:00am - 9:00am                    <\/div>\r\n\t\t\t        <div class=\"join-yoga-class\"><a class=\"yoga-join-now-btn\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-child-yoga\/\">\r\n                        <span class=\"effect\">Join now!<\/span>\r\n                        <span class=\"effect-hover\">Join now!<\/span>\r\n                    <\/a><\/div>\r\n\t    \t\t<\/div>\r\n\t    \t<\/div>\r\n\t\t<\/div>\r\n    <\/article>\r\n\r\n    \r\n\t\r\n\t\r\n    \r\n    \r\n\t\r\n\t<article class=\"col-xs-12 col-sm-6\">\r\n\t\t<div class=\"yoga-classes-wrap\">\r\n\t\t\t<h3 class=\"yoga-title-classes\">Class: Yoga For Beginners<\/h3>\r\n\t    \t<div class=\"yoga-class-content clearfix\">\r\n    \t\t\t<div class=\"yoga-image-classes\">\r\n                    <a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\">\r\n                        <img width=\"300\" height=\"200\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class8-300x200.jpg\" class=\"attachment-medium size-medium wp-post-image\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class8-300x200.jpg 300w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class8-768x512.jpg 768w, https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/class8.jpg 870w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>                    <\/a>\r\n                <\/div>\r\n\t    \t\t<div class=\"yoga-class-info\">\r\n\t    \t\t\t<div class=\"yoga-trainer\">teacher: Emily Blunt<\/div>\r\n\t\t\t    \t<div class=\"yoga-desc-class-1\">November 18, 2016<\/div>\r\n\t\t\t        <div class=\"yoga-desc-class-2\">\r\n                    10:00am - 11:00am                    <\/div>\r\n\t\t\t        <div class=\"join-yoga-class\"><a class=\"yoga-join-now-btn\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\">\r\n                        <span class=\"effect\">Join now!<\/span>\r\n                        <span class=\"effect-hover\">Join now!<\/span>\r\n                    <\/a><\/div>\r\n\t    \t\t<\/div>\r\n\t    \t<\/div>\r\n\t\t<\/div>\r\n    <\/article>\r\n\r\n        <\/div><!-- End Slide row -->\r\n\t\r\n\t    <\/li>\r\n\t\r\n\t\r\n            <\/ul>\r\n    <div id='carousel-custom-grid-dots' class='owl-dots'><\/div>\r\n<\/div>\r\n<script type=\"text\/javascript\">\r\n    jQuery(document).ready(function($){\r\n        var owl = $('#yoga-class-grid');\r\n        owl.owlCarousel({\r\n            items : 1,\r\n            margin: 0,\r\n                        loop: true,\r\n            center: false,\r\n            mouseDrag: true,\r\n            touchDrag: true,\r\n            pullDrag: true,\r\n            freeDrag: false,\r\n            stagePadding: 0,\r\n            merge: false,\r\n            mergeFit: true,\r\n            autoWidth: false,\r\n            startPosition: 0,\r\n            URLhashListener: false,\r\n            nav: false,\r\n            navText: ['next','prev'],\r\n            rewind: true,\r\n            navElement: 'div',\r\n            slideBy: 1,\r\n            dots: true,\r\n            dotsEach: false,\r\n            lazyLoad: false,\r\n            lazyContent: false,\r\n            autoplay: false,\r\n            autoHeight : true,\r\n            autoplayTimeout: 4000,\r\n            autoplayHoverPause: true,\r\n            smartSpeed: 250,\r\n            fluidSpeed: false,\r\n            autoplaySpeed: false,\r\n            navSpeed: false,\r\n            dotsSpeed: false,\r\n            dragEndSpeed: false,\r\n            responsive: {\r\n                0: {\r\n                    items: 1\r\n                },\r\n                500: {\r\n                    items: 1\r\n                },\r\n                991: {\r\n                    items: 1\r\n                },\r\n                1200: {\r\n                    items: 1\r\n                },\r\n                1300: {\r\n                    items: 1\r\n                }\r\n            },\r\n            responsiveRefreshRate: 200,\r\n            responsiveBaseElement: window,\r\n            video: false,\r\n            videoHeight: false,\r\n            videoWidth: false,\r\n            animateOut: false,\r\n            animateIn: false,\r\n            fallbackEasing: 'swing',\r\n            info: false,\r\n            nestedItemSelector: false,\r\n            itemElement: 'div',\r\n            stageElement: 'div',\r\n            navContainer: false,\r\n            dotsContainer: '#carousel-custom-grid-dots'\r\n        });\r\n        \/\/ Custom Navigation Events\r\n        $('#yoga-control').find(\".nav_next\").click(function() {\r\n            owl.trigger('next.owl.carousel');\r\n        });\r\n        $('#yoga-control').find(\".nav_prev\").click(function() {\r\n            owl.trigger('prev.owl.carousel');\r\n        });\r\n        \/\/ custom dot\r\n        $('.owl-dot').click(function () {\r\n            owl.trigger('to.owl.carousel', [$(this).index(), 1200]);\r\n        });\r\n    });\r\n<\/script>\r\n            <\/div>\r\n                [\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1474966310904{padding-top: 3% !important;padding-bottom: 3% !important;background-color: #64bc8f !important;}&#8221;][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1476160708509{padding-right: 0px !important;padding-left: 0px !important;}&#8221; offset=&#8221;vc_col-lg-3 vc_col-md-3&#8243;]                    <div class=\"counter-wrap-style_2 \" >\r\n                <div class=\"gr-counter gr-animated style_2   border_left\">\r\n  <div class=\"content-inner\">\r\n             <div class=\"icon-wrap\">\r\n             <img src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/snowed-mountains.png\"  alt=\"Member\">\r\n        <\/div>  \r\n       \r\n    <div class=\"counter-content\">\r\n      <div data-from=\"0\" data-to=\"531\" class=\"gr-number-counter\">\r\n        531      <\/div>\r\n      <div class=\"gr-text-defaul\">Member<\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>            <\/div>\r\n        [\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1476160719363{padding-right: 0px !important;padding-left: 0px !important;}&#8221; offset=&#8221;vc_col-lg-3 vc_col-md-3&#8243;]                    <div class=\"counter-wrap-style_2 \" >\r\n                <div class=\"gr-counter gr-animated style_2   border_left\">\r\n  <div class=\"content-inner\">\r\n             <div class=\"icon-wrap\">\r\n             <img src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/kayak.png\"  alt=\"Trainer\">\r\n        <\/div>  \r\n       \r\n    <div class=\"counter-content\">\r\n      <div data-from=\"0\" data-to=\"30\" class=\"gr-number-counter\">\r\n        30      <\/div>\r\n      <div class=\"gr-text-defaul\">Trainer<\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>            <\/div>\r\n        [\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1476160731115{padding-right: 0px !important;padding-left: 0px !important;}&#8221; offset=&#8221;vc_col-lg-3 vc_col-md-3&#8243;]                    <div class=\"counter-wrap-style_2 \" >\r\n                <div class=\"gr-counter gr-animated style_2   border_left\">\r\n  <div class=\"content-inner\">\r\n             <div class=\"icon-wrap\">\r\n             <img src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/bicycle-rider.png\"  alt=\"Activity\">\r\n        <\/div>  \r\n       \r\n    <div class=\"counter-content\">\r\n      <div data-from=\"0\" data-to=\"869\" class=\"gr-number-counter\">\r\n        869      <\/div>\r\n      <div class=\"gr-text-defaul\">Activity<\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>            <\/div>\r\n        [\/vc_column][vc_column width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1476160745059{padding-right: 0px !important;padding-left: 0px !important;}&#8221; offset=&#8221;vc_col-lg-3 vc_col-md-3&#8243;]                    <div class=\"counter-wrap-style_2 \" >\r\n                <div class=\"gr-counter gr-animated style_2 border_right  border_left\">\r\n  <div class=\"content-inner\">\r\n             <div class=\"icon-wrap\">\r\n             <img src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/cup.png\"  alt=\"Awards\">\r\n        <\/div>  \r\n       \r\n    <div class=\"counter-content\">\r\n      <div data-from=\"0\" data-to=\"120\" class=\"gr-number-counter\">\r\n        120      <\/div>\r\n      <div class=\"gr-text-defaul\">Awards<\/div>\r\n    <\/div>\r\n  <\/div>\r\n<\/div>            <\/div>\r\n        [\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1475305743582{margin-top: 5% !important;margin-bottom: 5% !important;background-color: #ffffff !important;}&#8221;][vc_column css=&#8221;.vc_custom_1475305812105{padding-top: 0px !important;padding-right: 0px !important;padding-left: 0px !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_custom_heading text=&#8221;Classes Timetable&#8221; font_container=&#8221;tag:h1|font_size:36px|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1475305825844{margin-top: 0px !important;margin-bottom: 3.5% !important;}&#8221;]<style type=\"text\/css\">.tt_tabs .tt_timetable .event{background: #ffffff;} .tt_tabs_navigation li a:hover, .tt_tabs_navigation li a.selected, .tt_tabs_navigation li.ui-tabs-active a{border-color:#64bc8f !important;}.tabs_box_navigation.sf-timetable-menu .tabs_box_navigation_selected{background-color:#64bc8f;border-color:#64bc8f;}.tabs_box_navigation.sf-timetable-menu .tabs_box_navigation_selected:hover{background-color: #FFF; border: 1px solid rgba(0, 0, 0, 0.1);}.sf-timetable-menu li ul li a:hover, .sf-timetable-menu li ul li.selected a:hover{background-color:#64bc8f;}<\/style><div class=\"timetable_clearfix tt_tabs tt_responsive event_layout_3\"><ul class=\"timetable_clearfix tt_tabs_navigation events_categories_filter\"><li><a href=\"#all-events\" title=\"All Events\">All Events<\/a><\/li><li><a href=\"#beginners-yoga\" title=\"Beginners Yoga\">Beginners Yoga<\/a><\/li><li><a href=\"#children-yoga\" title=\"Children Yoga\">Children Yoga<\/a><\/li><li><a href=\"#healthy-recipes\" title=\"Healthy Recipes\">Healthy Recipes<\/a><\/li><li><a href=\"#kundalm-yoga\" title=\"Kundalm Yoga\">Kundalm Yoga<\/a><\/li><\/ul><div id=\"all-events\"><table class=\"tt_timetable\">\r\n\t\t\t\t<thead>\r\n\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #f0f0f0 !important;\"><th><\/th>\t<th>Monday<\/th>\t<th>Tuesday<\/th>\t<th>Wednesday<\/th>\t<th>Thursday<\/th>\t<th>Friday<\/th>\t<th>Saturday<\/th>\t<th>Sunday<\/th>\t<\/tr>\r\n\t\t\t\t<\/thead>\r\n\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t7:00 am\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2433\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" style=\"color: #383838 !important;\">Healthy Recipes<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#64bc8f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Adam Rams<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2436\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" style=\"color: #383838 !important;\">Pratice With Children<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#ee6e9f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Vytas Skas<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2433\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" style=\"color: #383838 !important;\">Healthy Recipes<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#64bc8f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Adam Rams<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2436\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" style=\"color: #383838 !important;\">Pratice With Children<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#ee6e9f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Vytas Skas<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2433\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" style=\"color: #383838 !important;\">Healthy Recipes<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#64bc8f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Adam Rams<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2436\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" style=\"color: #383838 !important;\">Pratice With Children<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#ee6e9f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Vytas Skas<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2433\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" style=\"color: #383838 !important;\">Healthy Recipes<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_2 row_gray\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t8:00 am\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2521\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-child-yoga\/\" title=\"Basic Child Yoga\" style=\"color: #383838 !important;\">Basic Child Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#64bc8f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">8:00 am - 9:00 am<\/span><\/div><div class='after_hour_text'><span>Adam Rams<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2439\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/nature-yoga\/\" title=\"Nature Yoga\" style=\"color: #383838 !important;\">Nature Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">8:00 am - 9:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2439\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/nature-yoga\/\" title=\"Nature Yoga\" style=\"color: #383838 !important;\">Nature Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">8:00 am - 9:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_3\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t9:00 am\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2437\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" style=\"color: #383838 !important;\">Basic Kundalini<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_4 row_gray\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t10:00 am\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2437\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" style=\"color: #383838 !important;\">Basic Kundalini<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">10:00 am - 11:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2436\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" style=\"color: #383838 !important;\">Pratice With Children<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#ee6e9f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">10:00 am - 11:00 am<\/span><\/div><div class='after_hour_text'><span>Vytas Skas<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2437\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" style=\"color: #383838 !important;\">Basic Kundalini<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">10:00 am - 11:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2436\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" style=\"color: #383838 !important;\">Pratice With Children<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#ee6e9f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">10:00 am - 11:00 am<\/span><\/div><div class='after_hour_text'><span>Vytas Skas<\/span><\/div><\/div><\/td><td><\/td><\/tr><tr class=\"row_5\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t3:00 pm\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2432\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" style=\"color: #383838 !important;\">Yoga For Beginners<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#55d4f7\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">3:00 pm - 4:00 pm<\/span><\/div><div class='after_hour_text'><span>Mary Lyn<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2432\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" style=\"color: #383838 !important;\">Yoga For Beginners<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#55d4f7\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">3:00 pm - 4:00 pm<\/span><\/div><div class='after_hour_text'><span>Mary Lyn<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2432\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" style=\"color: #383838 !important;\">Yoga For Beginners<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#55d4f7\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">3:00 pm - 4:00 pm<\/span><\/div><div class='after_hour_text'><span>Mary Lyn<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">3:00 pm - 4:00 pm<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><\/tr><\/tbody>\r\n\t\t\t<\/table><div class=\"tt_timetable small\"><h3 class=\"box_header \">\r\n\t\t\t\t\tMonday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" class=\"event_header\">Healthy Recipes <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-child-yoga\/\" title=\"Basic Child Yoga\" class=\"event_header\">Basic Child Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t8:00 am - 9:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" class=\"event_header\">Basic Kundalini <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t10:00 am - 11:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" class=\"event_header\">Yoga For Beginners <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t3:00 pm - 4:00 pm\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tTuesday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" class=\"event_header\">Pratice With Children <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" class=\"event_header\">Basic Kundalini <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tWednesday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" class=\"event_header\">Healthy Recipes <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/nature-yoga\/\" title=\"Nature Yoga\" class=\"event_header\">Nature Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t8:00 am - 9:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" class=\"event_header\">Pratice With Children <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t10:00 am - 11:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" class=\"event_header\">Yoga For Beginners <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t3:00 pm - 4:00 pm\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tThursday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" class=\"event_header\">Pratice With Children <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" class=\"event_header\">Basic Kundalini <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t10:00 am - 11:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tFriday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" class=\"event_header\">Healthy Recipes <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/nature-yoga\/\" title=\"Nature Yoga\" class=\"event_header\">Nature Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t8:00 am - 9:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" class=\"event_header\">Yoga For Beginners <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t3:00 pm - 4:00 pm\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tSaturday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" class=\"event_header\">Pratice With Children <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" class=\"event_header\">Pratice With Children <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t10:00 am - 11:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tSunday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" class=\"event_header\">Healthy Recipes <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t3:00 pm - 4:00 pm\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"beginners-yoga\" class=\"tt-ui-tabs-hide\"><table class=\"tt_timetable\">\r\n\t\t\t\t<thead>\r\n\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #f0f0f0 !important;\"><th><\/th>\t<th>Monday<\/th>\t<th>Tuesday<\/th>\t<th>Wednesday<\/th>\t<th>Thursday<\/th>\t<th>Friday<\/th>\t<th>Saturday<\/th>\t<th>Sunday<\/th>\t<\/tr>\r\n\t\t\t\t<\/thead>\r\n\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t8:00 am\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2521\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-child-yoga\/\" title=\"Basic Child Yoga\" style=\"color: #383838 !important;\">Basic Child Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#64bc8f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">8:00 am - 9:00 am<\/span><\/div><div class='after_hour_text'><span>Adam Rams<\/span><\/div><\/div><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_2 row_gray\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t3:00 pm\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2432\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" style=\"color: #383838 !important;\">Yoga For Beginners<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#55d4f7\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">3:00 pm - 4:00 pm<\/span><\/div><div class='after_hour_text'><span>Mary Lyn<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2432\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" style=\"color: #383838 !important;\">Yoga For Beginners<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#55d4f7\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">3:00 pm - 4:00 pm<\/span><\/div><div class='after_hour_text'><span>Mary Lyn<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2432\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" style=\"color: #383838 !important;\">Yoga For Beginners<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#55d4f7\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">3:00 pm - 4:00 pm<\/span><\/div><div class='after_hour_text'><span>Mary Lyn<\/span><\/div><\/div><\/td><td><\/td><td><\/td><\/tr><\/tbody>\r\n\t\t\t<\/table><div class=\"tt_timetable small\"><h3 class=\"box_header \">\r\n\t\t\t\t\tMonday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-child-yoga\/\" title=\"Basic Child Yoga\" class=\"event_header\">Basic Child Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t8:00 am - 9:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" class=\"event_header\">Yoga For Beginners <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t3:00 pm - 4:00 pm\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tWednesday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" class=\"event_header\">Yoga For Beginners <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t3:00 pm - 4:00 pm\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tFriday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/yoga-for-beginners\/\" title=\"Yoga For Beginners\" class=\"event_header\">Yoga For Beginners <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t3:00 pm - 4:00 pm\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"children-yoga\" class=\"tt-ui-tabs-hide\"><table class=\"tt_timetable\">\r\n\t\t\t\t<thead>\r\n\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #f0f0f0 !important;\"><th><\/th>\t<th>Monday<\/th>\t<th>Tuesday<\/th>\t<th>Wednesday<\/th>\t<th>Thursday<\/th>\t<th>Friday<\/th>\t<th>Saturday<\/th>\t<th>Sunday<\/th>\t<\/tr>\r\n\t\t\t\t<\/thead>\r\n\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t7:00 am\r\n\t\t\t\t<\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2436\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" style=\"color: #383838 !important;\">Pratice With Children<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#ee6e9f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Vytas Skas<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2436\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" style=\"color: #383838 !important;\">Pratice With Children<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#ee6e9f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Vytas Skas<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2436\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" style=\"color: #383838 !important;\">Pratice With Children<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#ee6e9f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Vytas Skas<\/span><\/div><\/div><\/td><td><\/td><\/tr><tr class=\"row_2 row_gray\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t8:00 am\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2521\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-child-yoga\/\" title=\"Basic Child Yoga\" style=\"color: #383838 !important;\">Basic Child Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#64bc8f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">8:00 am - 9:00 am<\/span><\/div><div class='after_hour_text'><span>Adam Rams<\/span><\/div><\/div><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_3\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t10:00 am\r\n\t\t\t\t<\/td><td><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2436\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" style=\"color: #383838 !important;\">Pratice With Children<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#ee6e9f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">10:00 am - 11:00 am<\/span><\/div><div class='after_hour_text'><span>Vytas Skas<\/span><\/div><\/div><\/td><td><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2436\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" style=\"color: #383838 !important;\">Pratice With Children<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#ee6e9f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">10:00 am - 11:00 am<\/span><\/div><div class='after_hour_text'><span>Vytas Skas<\/span><\/div><\/div><\/td><td><\/td><\/tr><\/tbody>\r\n\t\t\t<\/table><div class=\"tt_timetable small\"><h3 class=\"box_header \">\r\n\t\t\t\t\tMonday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-child-yoga\/\" title=\"Basic Child Yoga\" class=\"event_header\">Basic Child Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t8:00 am - 9:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tTuesday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" class=\"event_header\">Pratice With Children <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tWednesday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" class=\"event_header\">Pratice With Children <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t10:00 am - 11:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tThursday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" class=\"event_header\">Pratice With Children <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tSaturday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" class=\"event_header\">Pratice With Children <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/pratice-with-children\/\" title=\"Pratice With Children\" class=\"event_header\">Pratice With Children <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t10:00 am - 11:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"healthy-recipes\" class=\"tt-ui-tabs-hide\"><table class=\"tt_timetable\">\r\n\t\t\t\t<thead>\r\n\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #f0f0f0 !important;\"><th><\/th>\t<th>Monday<\/th>\t<th>Tuesday<\/th>\t<th>Wednesday<\/th>\t<th>Thursday<\/th>\t<th>Friday<\/th>\t<th>Saturday<\/th>\t<th>Sunday<\/th>\t<\/tr>\r\n\t\t\t\t<\/thead>\r\n\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t7:00 am\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2433\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" style=\"color: #383838 !important;\">Healthy Recipes<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#64bc8f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Adam Rams<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2433\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" style=\"color: #383838 !important;\">Healthy Recipes<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#64bc8f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Adam Rams<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2433\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" style=\"color: #383838 !important;\">Healthy Recipes<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#64bc8f\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Adam Rams<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2433\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" style=\"color: #383838 !important;\">Healthy Recipes<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">7:00 am - 8:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_2 row_gray\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t8:00 am\r\n\t\t\t\t<\/td><td><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2439\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/nature-yoga\/\" title=\"Nature Yoga\" style=\"color: #383838 !important;\">Nature Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">8:00 am - 9:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2439\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/nature-yoga\/\" title=\"Nature Yoga\" style=\"color: #383838 !important;\">Nature Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">8:00 am - 9:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_3\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t9:00 am\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_4 row_gray\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t3:00 pm\r\n\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">3:00 pm - 4:00 pm<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><\/tr><\/tbody>\r\n\t\t\t<\/table><div class=\"tt_timetable small\"><h3 class=\"box_header \">\r\n\t\t\t\t\tMonday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" class=\"event_header\">Healthy Recipes <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tWednesday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" class=\"event_header\">Healthy Recipes <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/nature-yoga\/\" title=\"Nature Yoga\" class=\"event_header\">Nature Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t8:00 am - 9:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tFriday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" class=\"event_header\">Healthy Recipes <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/nature-yoga\/\" title=\"Nature Yoga\" class=\"event_header\">Nature Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t8:00 am - 9:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tSunday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/healthy-recipes\/\" title=\"Healthy Recipes\" class=\"event_header\">Healthy Recipes <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t7:00 am - 8:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t3:00 pm - 4:00 pm\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><div id=\"kundalm-yoga\" class=\"tt-ui-tabs-hide\"><table class=\"tt_timetable\">\r\n\t\t\t\t<thead>\r\n\t\t\t\t\t<tr class=\"row_gray\" style=\"background-color: #f0f0f0 !important;\"><th><\/th>\t<th>Monday<\/th>\t<th>Tuesday<\/th>\t<th>Wednesday<\/th>\t<th>Thursday<\/th>\t<th>Friday<\/th>\t<th>Saturday<\/th>\t<th>Sunday<\/th>\t<\/tr>\r\n\t\t\t\t<\/thead>\r\n\t\t\t\t<tbody><tr class=\"row_1\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t9:00 am\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2437\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" style=\"color: #383838 !important;\">Basic Kundalini<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">9:00 am - 10:00 am<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><\/tr><tr class=\"row_2 row_gray\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t10:00 am\r\n\t\t\t\t<\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2437\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" style=\"color: #383838 !important;\">Basic Kundalini<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">10:00 am - 11:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><td><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2437\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" style=\"color: #383838 !important;\">Basic Kundalini<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#444444\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">10:00 am - 11:00 am<\/span><\/div><div class='after_hour_text'><span>Chris Kane<\/span><\/div><\/div><\/td><td><\/td><td><\/td><td><\/td><\/tr><tr class=\"row_3\"><td class=\"tt_hours_column\">\r\n\t\t\t\t\t3:00 pm\r\n\t\t\t\t<\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td><\/td><td style=\"background: #ffffff;color: #383838;\" onMouseOver=\"this.style.background='#ffffff';this.style.color='#64bc8f';jQuery(this).find('.event_header').css('cssText', 'color: #64bc8f !important');jQuery(this).find('.hours').css('color','#383838');\" onMouseOut=\"this.style.background='#ffffff';this.style.color='#383838';jQuery(this).find('.event_header').css('cssText','color: #383838 !important');jQuery(this).find('.hours').css('color','#383838');\" class=\"event tt_single_event\"><div class=\"event_container id-2438\"><a class=\"event_header\" href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" style=\"color: #383838 !important;\">Advanced Yoga<\/a><div class='before_hour_text'><div class=\"timetable-make-color\" style=\"background-color:#f98e77\"><\/div><\/div><div class=\"hours_container\"><span class=\"hours\" style=\"color:#383838;\">3:00 pm - 4:00 pm<\/span><\/div><div class='after_hour_text'><span>Rose Cymbal<\/span><\/div><\/div><\/td><\/tr><\/tbody>\r\n\t\t\t<\/table><div class=\"tt_timetable small\"><h3 class=\"box_header \">\r\n\t\t\t\t\tMonday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" class=\"event_header\">Basic Kundalini <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t10:00 am - 11:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tTuesday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" class=\"event_header\">Basic Kundalini <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tWednesday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tThursday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/basic-kundalini\/\" title=\"Basic Kundalini\" class=\"event_header\">Basic Kundalini <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t10:00 am - 11:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tFriday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><h3 class=\"box_header  page_margin_top\">\r\n\t\t\t\t\tSunday\r\n\t\t\t\t<\/h3>\r\n\t\t\t\t<ul class=\"tt_items_list thin page_margin_top timetable_clearfix\">\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t9:00 am - 10:00 am\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li>\r\n\t\t\t\t\t\t\t<li class=\"timetable_clearfix\">\r\n\t\t\t\t\t\t\t\t<div class=\"event_container\">\r\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/demo.yolotheme.com\/behealth\/class\/advanced-yoga\/\" title=\"Advanced Yoga\" class=\"event_header\">Advanced Yoga <\/a><\/div><div class=\"value\">\r\n\t\t\t\t\t\t\t\t\t3:00 pm - 4:00 pm\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<\/li><\/ul><\/div><\/div><\/div><div id='tt_error_message' class='tt_hide'>No events available!<\/div>[\/vc_column][\/vc_row][vc_row layout=&#8221;wide&#8221;][vc_column css=&#8221;.vc_custom_1476171219368{padding-top: 0px !important;}&#8221;][vc_row_inner equal_height=&#8221;yes&#8221;][vc_column_inner css=&#8221;.vc_custom_1478494407254{padding-top: 0px !important;padding-right: 0px !important;padding-left: 0px !important;}&#8221; offset=&#8221;vc_col-lg-6 vc_col-md-12&#8243;]  \r\n                    <div class=\"recent-news-home_5 \" >\r\n                <div class=\"recent-news-container\">\r\n  <ul id=\"recent-news-list-6a0431b4af79b\" class=\"recent-news-list owl-carousel\"\r\n    data-owl=\"1\"\r\n    data-rtl=\"\"\r\n    data-loop=\"true\"\r\n    data-nav=\"true\"\r\n    data-autoplay=\"true\"\r\n    data-duration=\"\"\r\n  >\r\n                      <li class=\"recent-news-item\"><!-- Slide item -->\r\n      \r\n                  <div class=\"row\"><!-- Slide row -->\r\n                    <article class=\"col-xs-12 col-sm-12 col-md-12\">\r\n              <div class=\"post-thumbnail\" >\r\n                <div class=\"post-bg-img\" style=\"background:url('https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/08\/donec-quis-ex-vel-tincidunt.jpg')\">\r\n                  \r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"post-information\">\r\n                <h3 class=\"post-blog-title\"><a href=\"https:\/\/demo.yolotheme.com\/behealth\/a-yoga-sequence-to-help-you-commit\/\">A Yoga Sequence to Help You Commit<\/a><\/h3>\r\n                <div class=\"info-meta\">\r\n                  <span class=\"entry-post-date\"><i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i>  August 1, 2016<\/span>\r\n                  <span class=\"post-count-comments\"><i class=\"fa fa-comments\"><\/i>1 Comments<\/span>\r\n                <\/div>\r\n                <p class=\"post-blog-excerpt\">What has surprised you most about being a father? Having children was always part of my vision, but as...<\/p>\r\n                <div class=\"polygon\"><\/div>\r\n                <a class=\"btn-rm\" href=\"https:\/\/demo.yolotheme.com\/behealth\/a-yoga-sequence-to-help-you-commit\/\">Read More<\/a>\r\n              <\/div>\r\n            <\/article>\r\n                  <\/div>\r\n        \r\n      \r\n                      \r\n                  <div class=\"row\"><!-- Slide row -->\r\n                    <article class=\"col-xs-12 col-sm-12 col-md-12\">\r\n              <div class=\"post-thumbnail\" >\r\n                <div class=\"post-bg-img\" style=\"background:url('https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/08\/practising-yoga-on-the-sea-shore-is-a-good-method.jpg')\">\r\n                  \r\n                <\/div>\r\n              <\/div>\r\n              <div class=\"post-information\">\r\n                <h3 class=\"post-blog-title\"><a href=\"https:\/\/demo.yolotheme.com\/behealth\/practising-yoga-on-the-sea-shore-is-a-good-method\/\">Practising yoga on the sea shore is a good method<\/a><\/h3>\r\n                <div class=\"info-meta\">\r\n                  <span class=\"entry-post-date\"><i class=\"fa fa-calendar\" aria-hidden=\"true\"><\/i>  August 1, 2016<\/span>\r\n                  <span class=\"post-count-comments\"><i class=\"fa fa-comments\"><\/i>0 Comments<\/span>\r\n                <\/div>\r\n                <p class=\"post-blog-excerpt\">What has surprised you most about being a father? Having children was always part of my vision, but as...<\/p>\r\n                <div class=\"polygon\"><\/div>\r\n                <a class=\"btn-rm\" href=\"https:\/\/demo.yolotheme.com\/behealth\/practising-yoga-on-the-sea-shore-is-a-good-method\/\">Read More<\/a>\r\n              <\/div>\r\n            <\/article>\r\n                  <\/div>\r\n        \r\n            <\/li>\r\n      \r\n            <\/ul>\r\n<\/div>   \r\n\r\n            <\/div>\r\n            \r\n                [\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1478494489991{background-image: url(https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/banner-h5.jpg?id=4282) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; offset=&#8221;vc_col-lg-6 vc_col-md-12 vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1475307370361{padding-top: 5% !important;padding-bottom: 5% !important;}&#8221;][vc_column css=&#8221;.vc_custom_1471242288450{padding-right: 0px !important;padding-left: 0px !important;}&#8221;]                        <div class=\" \" >\r\n                <div class=\"style_2 clients-shortcode-wrap\">\r\n    <div id=\"clients-list-6a0431b4b2a38\" class=\"clients-list owl-carousel\"\r\n        data-owl=\"5\"\r\n        data-autoplay=\"true\"\r\n        data-loop=\"true\",\r\n        data-nav=\"true\"\r\n        data-rtl=\"\"\r\n        data-duration=\"3000\"\r\n    >\r\n            \t<div class=\"client-item\">\r\n        <a href=\"#\">\r\n            <img class=\"img-responsive\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/logo-client1.png\"  alt=\"Logo 1\">\r\n        <\/a>\r\n        <\/div>\r\n            \t<div class=\"client-item\">\r\n        <a href=\"#\">\r\n            <img class=\"img-responsive\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/logo-client2.png\"  alt=\"Logo 2\">\r\n        <\/a>\r\n        <\/div>\r\n            \t<div class=\"client-item\">\r\n        <a href=\"#\">\r\n            <img class=\"img-responsive\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/logo-client3.png\"  alt=\"Logo 3\">\r\n        <\/a>\r\n        <\/div>\r\n            \t<div class=\"client-item\">\r\n        <a href=\"#\">\r\n            <img class=\"img-responsive\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/logo-client4.png\"  alt=\"Logo 4\">\r\n        <\/a>\r\n        <\/div>\r\n            \t<div class=\"client-item\">\r\n        <a href=\"#\">\r\n            <img class=\"img-responsive\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/logo-client5.png\"  alt=\"Logo 5\">\r\n        <\/a>\r\n        <\/div>\r\n            \t<div class=\"client-item\">\r\n        <a href=\"#\">\r\n            <img class=\"img-responsive\" src=\"https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/07\/logo-client6.png\"  alt=\"Logo 6\">\r\n        <\/a>\r\n        <\/div>\r\n            <\/div>\r\n<\/div>\r\n            <\/div>\r\n                    [\/vc_column][\/vc_row][vc_row layout=&#8221;wide&#8221;][vc_column css=&#8221;.vc_custom_1476172597013{padding-right: 0px !important;padding-left: 0px !important;}&#8221;][vc_custom_heading text=&#8221;Follow Us On Instagram!&#8221; font_container=&#8221;tag:h1|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1475309376587{margin-top: 0px !important;}&#8221;][vc_icon icon_fontawesome=&#8221;fa fa-instagram&#8221; color=&#8221;black&#8221; size=&#8221;lg&#8221; align=&#8221;center&#8221; el_class=&#8221;sc-iconlink&#8221;]\n            <div \n                class=\"elfsight-widget-instagram-feed elfsight-widget\" \n                data-elfsight-instagram-feed-options=\"%7B%22sourceType%22%3A%22personalAccount%22%2C%22apiChangesMessage%22%3Anull%2C%22source%22%3A%5B%5D%2C%22personalAccessToken%22%3A%2219f3679a-9a2c-4083-b91b-be8f90b72e14%22%2C%22businessAccessToken%22%3A%22fc8be3d5-d4e6-47fd-a60f-928780455ff1%22%2C%22businessAccount%22%3A%7B%22value%22%3A%2217841402340279740%22%2C%22username%22%3A%22yolotheme%22%7D%2C%22businessHashtag%22%3A%22%23yogapractice%22%2C%22filterOnly%22%3A%5B%5D%2C%22filterExcept%22%3A%5B%5D%2C%22limit%22%3A8%2C%22order%22%3A%22date%22%2C%22layout%22%3A%22slider%22%2C%22postTemplate%22%3A%22tile%22%2C%22columns%22%3A8%2C%22rows%22%3A1%2C%22gutter%22%3A0%2C%22responsive%22%3A%5B%7B%22minWidth%22%3A375%2C%22columns%22%3A1%2C%22rows%22%3A1%2C%22gutter%22%3A%220%22%7D%2C%7B%22minWidth%22%3A768%2C%22columns%22%3A3%2C%22rows%22%3A2%2C%22gutter%22%3A%220%22%7D%5D%2C%22width%22%3A%22auto%22%2C%22callToActionButtons%22%3A%5B%7B%22postUrl%22%3A%22https%3A%5C%2F%5C%2Fwww.instagram.com%5C%2Fp%5C%2FBmr7eH0nyxQ%5C%2F%22%2C%22buttonLabel%22%3A%22Install%20Instagram%20Feed%20now%22%2C%22buttonLink%22%3A%22https%3A%5C%2F%5C%2Felfsight.com%5C%2Finstagram-feed-instashow%5C%2F%22%7D%2C%7B%22postUrl%22%3A%22https%3A%5C%2F%5C%2Fwww.instagram.com%5C%2Fp%5C%2FBmgZy5FnnQB%5C%2F%22%2C%22buttonLabel%22%3A%22Install%20Instagram%20Feed%20now%22%2C%22buttonLink%22%3A%22https%3A%5C%2F%5C%2Felfsight.com%5C%2Finstagram-feed-instashow%5C%2F%22%7D%2C%7B%22postUrl%22%3A%22https%3A%5C%2F%5C%2Fwww.instagram.com%5C%2Fp%5C%2FBmbbCfBndRU%5C%2F%22%2C%22buttonLabel%22%3A%22Install%20Instagram%20Feed%20now%22%2C%22buttonLink%22%3A%22https%3A%5C%2F%5C%2Felfsight.com%5C%2Finstagram-feed-instashow%5C%2F%22%7D%5D%2C%22postElements%22%3A%5B%22user%22%2C%22date%22%2C%22instagramLink%22%2C%22likesCount%22%2C%22commentsCount%22%2C%22share%22%2C%22text%22%5D%2C%22popupElements%22%3A%5B%22user%22%2C%22location%22%2C%22followButton%22%2C%22instagramLink%22%2C%22likesCount%22%2C%22share%22%2C%22text%22%2C%22comments%22%2C%22date%22%5D%2C%22imageClickAction%22%3A%22popup%22%2C%22sliderArrows%22%3Atrue%2C%22sliderDrag%22%3Atrue%2C%22sliderSpeed%22%3A0.59999999999999998%2C%22sliderAutoplay%22%3A%22%22%2C%22colorScheme%22%3A%22default%22%2C%22colorPostOverlayBg%22%3A%22rgba%280%2C%200%2C%200%2C%200.8%29%22%2C%22colorPostOverlayText%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22colorPostBg%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22colorPostText%22%3A%22rgb%280%2C%200%2C%200%29%22%2C%22colorPostLinks%22%3A%22rgb%280%2C%2053%2C%20107%29%22%2C%22colorSliderArrows%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22colorSliderArrowsBg%22%3A%22rgba%280%2C%200%2C%200%2C%200.9%29%22%2C%22colorGridLoadMoreButton%22%3A%22rgb%2856%2C%20151%2C%20240%29%22%2C%22colorPopupOverlay%22%3A%22rgba%2843%2C%2043%2C%2043%2C%200.9%29%22%2C%22colorPopupBg%22%3A%22rgb%28255%2C%20255%2C%20255%29%22%2C%22colorPopupText%22%3A%22rgb%280%2C%200%2C%200%29%22%2C%22colorPopupLinks%22%3A%22rgb%280%2C%2053%2C%20105%29%22%2C%22colorPopupFollowButton%22%3A%22rgb%2856%2C%20151%2C%20240%29%22%2C%22colorPopupCtaButton%22%3A%22rgb%2856%2C%20151%2C%20240%29%22%2C%22widgetTitle%22%3A%22%22%2C%22lang%22%3A%22en%22%2C%22apiUrl%22%3A%22https%3A%5C%2F%5C%2Fdemo.yolotheme.com%5C%2Fbehealth%5C%2Fwp-json%5C%2Felfsight-instagram-feed%5C%2Fapi%22%2C%22apiProxyUrl%22%3A%22https%3A%5C%2F%5C%2Fdemo.yolotheme.com%5C%2Fbehealth%5C%2Fwp-json%5C%2Felfsight-instagram-feed%22%2C%22widgetId%22%3A%221%22%7D\" \n                data-elfsight-instagram-feed-version=\"4.0.2\"\n                data-elfsight-widget-id=\"elfsight-instagram-feed-1\">\n            <\/div>\n            [\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][rev_slider_vc alias=&#8221;home-5&#8243;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1475305334529{margin-top: 5% !important;margin-bottom: 3% !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;Welcome to BeHealth.&#8221; font_container=&#8221;tag:h2|font_size:48px|text_align:center|color:%230c0c0c&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1475305228183{margin-top: 0px !important;margin-bottom: 0px !important;}&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1474884525604{padding-top: 2% !important;padding-bottom: 4% !important;}&#8221;][vc_column offset=&#8221;vc_col-lg-5 vc_col-md-5&#8243; css=&#8221;.vc_custom_1476159651333{margin-bottom: 20px !important;}&#8221;][vc_single_image image=&#8221;3391&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column][vc_column offset=&#8221;vc_col-lg-7 vc_col-md-7&#8243;][vc_row_inner css=&#8221;.vc_custom_1474885701018{padding-right: 0px !important;padding-left: 0px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row parallax=&#8221;content-moving&#8221; css=&#8221;.vc_custom_1477044512260{padding-top: 5% !important;padding-bottom: 3% !important;background-image: url(https:\/\/demo.yolotheme.com\/behealth\/wp-content\/uploads\/2016\/09\/bg-paralax4.jpg?id=4880) !important;background-position: center;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column][vc_custom_heading text=&#8221;News Events Of&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/demo.yolotheme.com\/behealth\/wp-json\/wp\/v2\/pages\/4146"}],"collection":[{"href":"https:\/\/demo.yolotheme.com\/behealth\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/demo.yolotheme.com\/behealth\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/demo.yolotheme.com\/behealth\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/demo.yolotheme.com\/behealth\/wp-json\/wp\/v2\/comments?post=4146"}],"version-history":[{"count":0,"href":"https:\/\/demo.yolotheme.com\/behealth\/wp-json\/wp\/v2\/pages\/4146\/revisions"}],"wp:attachment":[{"href":"https:\/\/demo.yolotheme.com\/behealth\/wp-json\/wp\/v2\/media?parent=4146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}